{"id":144,"date":"2020-05-28T15:56:27","date_gmt":"2020-05-28T15:56:27","guid":{"rendered":"http:\/\/euroguaina.com\/?page_id=144"},"modified":"2020-06-02T12:19:06","modified_gmt":"2020-06-02T12:19:06","slug":"mapeplan-wt-15-1-5-mm","status":"publish","type":"page","link":"http:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/","title":{"rendered":"Mapeplan WT 15  1.5 mm"},"content":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_single_image image=&#8221;145&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;55&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Mapeplan WT 15 1.5 mm&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_column_text]<\/p>\n<div class=\"col-xs-12 div-certificati hidden-xs hidden-sm\">\n<div class=\"txtl npa\">\n<div class=\"col-xs-12 div-certificati hidden-xs hidden-sm\">\n<div class=\"txtl npa\">\n<div class=\"col-xs-12 div-certificati hidden-xs hidden-sm\">\n<div class=\"txtl npa\">\n<div class=\"col-xs-12 div-certificati hidden-xs hidden-sm\">\n<div class=\"txtl npa\">\n<h4 class=\"tit-prodotti txtcxm\">Cilesi e garantuar:<\/h4>\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"col-xs-2 omt omb npl pad-right25 hidden-xs hidden-sm\"><img decoding=\"async\" title=\"Green Building Council ITALIA\" src=\"http:\/\/www.polyglass.com\/public\/COM\/Certificato\/small\/logo-green.jpg\" alt=\"Green Building Council ITALIA\" \/><\/div>\n<\/div>\n<div class=\"col-xs-12 npa document-txt pad-bottom15 pad-top15\"><strong>Mapeplan<sup>\u00ae<\/sup>\u00a0WT<\/strong>\u00a0\u00e8 un manto impermeabile sintetico in PVC-P prodotto mediante un processo di multi-extrusion, con materie prime di alta qualit\u00e0. Mapeplan<sup>\u00ae<\/sup>\u00a0WT \u00e8 conforme alle norme EN 13361 e EN 13362.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_custom_heading text=&#8221;Dokumentet e bashkangjitura:&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_row_inner][vc_column_inner]<div class=\"aio-icon-component    style_1\"><a class=\"aio-icon-box-link\" href=\"\/wp-content\/uploads\/2020\/05\/Mapeplan_WT_ITA_07_16.pdf\" target=\"_blank\" rel=\"noopener\" ><div id=\"Info-box-wrap-4087\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:50px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"null\" src=\"http:\/\/euroguaina.com\/wp-content\/uploads\/2020\/05\/PDF-Download-button.png\"\/>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-4087 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  style=\"\">Skeda teknike<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/a><\/div> <!-- aio-icon-component -->[vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_single_image image=&#8221;145&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;55&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Mapeplan WT 15 1.5 mm&#8221; font_container=&#8221;tag:h3|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_column_text] Cilesi e garantuar: &nbsp; Mapeplan\u00ae\u00a0WT\u00a0\u00e8 un manto impermeabile sintetico in PVC-P prodotto mediante un processo di multi-extrusion, con materie prime di alta qualit\u00e0. Mapeplan\u00ae\u00a0WT \u00e8 conforme alle norme EN 13361 e EN 13362. [\/vc_column_text][vc_custom_heading text=&#8221;Dokumentet e&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-144","page","type-page","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mapeplan WT 15 1.5 mm - Materiale Hidro Termo-Izoluese. Euro Guaina Shpk<\/title>\n<meta name=\"description\" content=\"Euro Guaina Shpk. Materiale Hidro Izoluese. Materiale Termo Hizoluese. PVC &amp; TPO. Shitje me Shumic edhe Pakice. Ju Mirepresim!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapeplan WT 15 1.5 mm - Materiale Hidro Termo-Izoluese. Euro Guaina Shpk\" \/>\n<meta property=\"og:description\" content=\"Euro Guaina Shpk. Materiale Hidro Izoluese. Materiale Termo Hizoluese. PVC &amp; TPO. Shitje me Shumic edhe Pakice. Ju Mirepresim!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Materiale Hidro Termo-Izoluese. Euro Guaina Shpk\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-02T12:19:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.polyglass.com\/public\/COM\/Certificato\/small\/logo-green.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euroguaina.com\\\/index.php\\\/mapeplan-wt-15-1-5-mm\\\/\",\"url\":\"https:\\\/\\\/euroguaina.com\\\/index.php\\\/mapeplan-wt-15-1-5-mm\\\/\",\"name\":\"Mapeplan WT 15 1.5 mm - Materiale Hidro Termo-Izoluese. Euro Guaina Shpk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euroguaina.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euroguaina.com\\\/index.php\\\/mapeplan-wt-15-1-5-mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euroguaina.com\\\/index.php\\\/mapeplan-wt-15-1-5-mm\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.polyglass.com\\\/public\\\/COM\\\/Certificato\\\/small\\\/logo-green.jpg\",\"datePublished\":\"2020-05-28T15:56:27+00:00\",\"dateModified\":\"2020-06-02T12:19:06+00:00\",\"description\":\"Euro Guaina Shpk. Materiale Hidro Izoluese. Materiale Termo Hizoluese. PVC & TPO. Shitje me Shumic edhe Pakice. Ju Mirepresim!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euroguaina.com\\\/index.php\\\/mapeplan-wt-15-1-5-mm\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euroguaina.com\\\/index.php\\\/mapeplan-wt-15-1-5-mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/euroguaina.com\\\/index.php\\\/mapeplan-wt-15-1-5-mm\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.polyglass.com\\\/public\\\/COM\\\/Certificato\\\/small\\\/logo-green.jpg\",\"contentUrl\":\"http:\\\/\\\/www.polyglass.com\\\/public\\\/COM\\\/Certificato\\\/small\\\/logo-green.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euroguaina.com\\\/index.php\\\/mapeplan-wt-15-1-5-mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/euroguaina.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapeplan WT 15 1.5 mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euroguaina.com\\\/#website\",\"url\":\"https:\\\/\\\/euroguaina.com\\\/\",\"name\":\"Materiale Hidro Termo-Izoluese. Euro Guaina Shpk\",\"description\":\"Materiale PVC &amp; TPO, Membrana Bituminoze, Aksesore izolues, Aksesore Termoizolues\",\"publisher\":{\"@id\":\"https:\\\/\\\/euroguaina.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euroguaina.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/euroguaina.com\\\/#organization\",\"name\":\"Materiale Hidro Termo-Izoluese. Euro Guaina Shpk\",\"url\":\"https:\\\/\\\/euroguaina.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/euroguaina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/euroguaina.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo.png\",\"contentUrl\":\"http:\\\/\\\/euroguaina.com\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo.png\",\"width\":447,\"height\":90,\"caption\":\"Materiale Hidro Termo-Izoluese. Euro Guaina Shpk\"},\"image\":{\"@id\":\"https:\\\/\\\/euroguaina.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/instagram.com\\\/euroguaina\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapeplan WT 15 1.5 mm - Materiale Hidro Termo-Izoluese. Euro Guaina Shpk","description":"Euro Guaina Shpk. Materiale Hidro Izoluese. Materiale Termo Hizoluese. PVC & TPO. Shitje me Shumic edhe Pakice. Ju Mirepresim!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/","og_locale":"sq_AL","og_type":"article","og_title":"Mapeplan WT 15 1.5 mm - Materiale Hidro Termo-Izoluese. Euro Guaina Shpk","og_description":"Euro Guaina Shpk. Materiale Hidro Izoluese. Materiale Termo Hizoluese. PVC & TPO. Shitje me Shumic edhe Pakice. Ju Mirepresim!","og_url":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/","og_site_name":"Materiale Hidro Termo-Izoluese. Euro Guaina Shpk","article_modified_time":"2020-06-02T12:19:06+00:00","og_image":[{"url":"http:\/\/www.polyglass.com\/public\/COM\/Certificato\/small\/logo-green.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/","url":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/","name":"Mapeplan WT 15 1.5 mm - Materiale Hidro Termo-Izoluese. Euro Guaina Shpk","isPartOf":{"@id":"https:\/\/euroguaina.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/#primaryimage"},"image":{"@id":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/#primaryimage"},"thumbnailUrl":"http:\/\/www.polyglass.com\/public\/COM\/Certificato\/small\/logo-green.jpg","datePublished":"2020-05-28T15:56:27+00:00","dateModified":"2020-06-02T12:19:06+00:00","description":"Euro Guaina Shpk. Materiale Hidro Izoluese. Materiale Termo Hizoluese. PVC & TPO. Shitje me Shumic edhe Pakice. Ju Mirepresim!","breadcrumb":{"@id":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/#primaryimage","url":"http:\/\/www.polyglass.com\/public\/COM\/Certificato\/small\/logo-green.jpg","contentUrl":"http:\/\/www.polyglass.com\/public\/COM\/Certificato\/small\/logo-green.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/euroguaina.com\/index.php\/mapeplan-wt-15-1-5-mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/euroguaina.com\/"},{"@type":"ListItem","position":2,"name":"Mapeplan WT 15 1.5 mm"}]},{"@type":"WebSite","@id":"https:\/\/euroguaina.com\/#website","url":"https:\/\/euroguaina.com\/","name":"Materiale Hidro Termo-Izoluese. Euro Guaina Shpk","description":"Materiale PVC &amp; TPO, Membrana Bituminoze, Aksesore izolues, Aksesore Termoizolues","publisher":{"@id":"https:\/\/euroguaina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euroguaina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/euroguaina.com\/#organization","name":"Materiale Hidro Termo-Izoluese. Euro Guaina Shpk","url":"https:\/\/euroguaina.com\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/euroguaina.com\/#\/schema\/logo\/image\/","url":"http:\/\/euroguaina.com\/wp-content\/uploads\/2020\/05\/logo.png","contentUrl":"http:\/\/euroguaina.com\/wp-content\/uploads\/2020\/05\/logo.png","width":447,"height":90,"caption":"Materiale Hidro Termo-Izoluese. Euro Guaina Shpk"},"image":{"@id":"https:\/\/euroguaina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/instagram.com\/euroguaina"]}]}},"_links":{"self":[{"href":"http:\/\/euroguaina.com\/index.php\/wp-json\/wp\/v2\/pages\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/euroguaina.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/euroguaina.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/euroguaina.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/euroguaina.com\/index.php\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":0,"href":"http:\/\/euroguaina.com\/index.php\/wp-json\/wp\/v2\/pages\/144\/revisions"}],"wp:attachment":[{"href":"http:\/\/euroguaina.com\/index.php\/wp-json\/wp\/v2\/media?parent=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}